{"id":15,"date":"2019-12-06T17:31:04","date_gmt":"2019-12-06T16:31:04","guid":{"rendered":"http:\/\/www.ehpc-conseils.com\/?page_id=15"},"modified":"2020-02-13T15:28:30","modified_gmt":"2020-02-13T14:28:30","slug":"accueil","status":"publish","type":"page","link":"https:\/\/www.ehpc-conseils.com\/","title":{"rendered":"ACCUEIL"},"content":{"rendered":"\n<div class=\"slider-wrapper relative\" id=\"slider-1546597977\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover is-full-height has-parallax\" id=\"banner-1164462682\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-4\" data-parallax-container=\".banner\" data-parallax-background>\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-2012964809\" class=\"text-box banner-layer x50 md-x50 lg-x50 y20 md-y20 lg-y25 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h5><span data-text-color=\"alert\">LE CABINET<\/span><\/h5>\n<h2 class=\"uppercase\"><span data-text-color=\"alert\">d&rsquo;EXPERTISE COMPTABLE<\/span><\/h2>\n<h5 class=\"uppercase\"><span data-text-color=\"alert\">que vous attendiez !<\/span><\/h5>\n<a href=\"#voir-le-site\" target=\"_self\" class=\"button white is-gradient box-shadow-2\"  style=\"border-radius:99px;\">\n    <span>En savoir plus<\/span>\n  <\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2012964809 .text-inner {\n  padding: 30px 30px 30px 30px;\n}\n#text-box-2012964809 {\n  width: 90%;\n}\n#text-box-2012964809 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-2012964809 {\n    width: 75%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1164462682 {\n  padding-top: 100%;\n}\n#banner-1164462682 .bg.bg-loaded {\n  background-image: url(https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/ehpc-conseils.jpg);\n}\n#banner-1164462682 .overlay {\n  background-color: rgba(180, 215, 188, 0.59);\n}\n#banner-1164462682 .bg {\n  background-position: 0% 38%;\n}\n#banner-1164462682 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1164462682 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n@media (min-width:550px) {\n  #banner-1164462682 {\n    padding-top: 100%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #voir-le-site\" data-bullet=\"false\" data-link=\"#voir-le-site\" data-title=\"voir-le-site\"><a name=\"voir-le-site\"><\/a><\/span>\n\n<div class=\"row row-collapse row-full-width align-middle align-center\"  id=\"row-935538152\">\n\n\n\t<div id=\"col-899052851\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1382142346\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1382142346 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"uppercase\" style=\"text-align: center;\" align=\"justify\">EHPC Conseils, <br \/>un juste \u00e9quilibre entre le digital et l&rsquo;humain<\/h2>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:120px;\"><\/div><\/div>\n\n<p style=\"text-align: center;\" align=\"justify\">Professionnel lib\u00e9ral, commer\u00e7ant, artisan, TPE, PME, cr\u00e9ateur d&rsquo;entreprise, \u00e0 la recherche d\u2019un expert-comptable ?<\/p>\n<p style=\"text-align: center;\" align=\"justify\">Le cabinet d&rsquo;expertise comptable EHPC Conseils est l\u00e0 pour vous accompagner dans vos projets professionnels et vos ambitions de croissance.<\/p>\n<a href=\"https:\/\/www.ehpc-conseils.com\/index.php\/notre-cabinet\/\" target=\"_self\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>D\u00e9couvrez le cabinet<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1560822257\" class=\"col medium-4 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1441750497\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-2 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"5472\" height=\"3648\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/IMG_1422.jpg\" class=\"attachment-original size-original\" alt=\"pascale combabessou et Emilie humbrecht\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/IMG_1422.jpg 5472w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/IMG_1422-300x200.jpg 300w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/IMG_1422-1024x683.jpg 1024w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/IMG_1422-768x512.jpg 768w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/IMG_1422-1536x1024.jpg 1536w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/IMG_1422-2048x1365.jpg 2048w\" sizes=\"(max-width: 5472px) 100vw, 5472px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1441750497 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<section class=\"section\" id=\"section_463886623\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-983615229\">\n\n\n\t<div id=\"col-2052345035\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h1 class=\"uppercase\" style=\"text-align: center;\">NOTRE APPLICATION MOBILE<\/h1>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:120px;\"><\/div><\/div>\n\n<p style=\"text-align: center;\">Une application d\u00e9di\u00e9e disponible sur Apple Store et Andro\u00efd :<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-middle\"  id=\"row-1974012895\">\n\n\n\t<div id=\"col-605233570\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-370910497\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-370910497 {\n  padding-top: 31px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-697532654\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-697532654 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<a class=\"plain\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.activity.ehpc\" target=\"_blank\" rel=\"noopener noreferrer\" >\t<div class=\"icon-box featured-box icon-box-center text-center is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 64px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"252\" height=\"297\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/android.png\" class=\"attachment-medium size-medium\" alt=\"picto de l&#039;application android de la soci\u00e9t\u00e9 de comptabilit\u00e9 EHPC Conseils\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">ANDROID<\/h5>\t\t\t\t\t\t\n\n\t<div id=\"gap-2088440825\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2088440825 {\n  padding-top: 35px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1492455300\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2058723943\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:230px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3508\" height=\"2054\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/BAT_EHPC.jpg\" class=\"attachment-original size-original\" alt=\"application mobile du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 Emilie humbrecht et pascale combabessou\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/BAT_EHPC.jpg 3508w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/BAT_EHPC-300x176.jpg 300w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/BAT_EHPC-768x450.jpg 768w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/BAT_EHPC-1024x600.jpg 1024w\" sizes=\"(max-width: 3508px) 100vw, 3508px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2058723943 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1727723129\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-2001278549\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2001278549 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-1881797793\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1881797793 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<a class=\"plain\" href=\"https:\/\/apps.apple.com\/bz\/app\/ehpc-conseils\/id1490244672\" target=\"_blank\" rel=\"noopener noreferrer\" >\t<div class=\"icon-box featured-box icon-box-center text-center is-large\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 64px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"254\" height=\"296\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/appel-store.png\" class=\"attachment-medium size-medium\" alt=\"picto de l&#039;application apple store de la soci\u00e9t\u00e9 de comptabilit\u00e9 EHPC Conseils\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">APP STORE<\/h5>\t\t\t\t\t\t\n\n\t<div id=\"gap-1139141556\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1139141556 {\n  padding-top: 31px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\t<div id=\"gap-732682043\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-732682043 {\n  padding-top: 23px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1821511901\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1821511901 {\n  padding-top: 31px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_463886623 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(193, 193, 193);\n}\n#section_463886623 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n#section_463886623 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_463886623 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1893534360\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1359530199\">\n\n\n\t<div id=\"col-687744813\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1972405844\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1972405844 {\n  padding-top: 31px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h1 class=\"uppercase\" style=\"text-align: center;\">NOTRE POINT FORT : VOTRE UNIVERS DIGITAL<\/h1>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:120px;\"><\/div><\/div>\n\n<p align=\"center\">Le cabinet d&rsquo;expertise comptable EHPC Conseils vous assure des outils digitaux tout au long de notre collaboration :<\/p>\n\t<div id=\"gap-420631553\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-420631553 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-large align-center\"  id=\"row-523592441\">\n\n\n\t<div id=\"col-969911220\" class=\"col medium-4 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-ponctualite.png\" class=\"attachment-medium size-medium\" alt=\"picto exprimant la ponctualit\u00e9 et les notifications du logiciel client - contact EHPC Conseils pascale combabessou\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-ponctualite.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-ponctualite-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h4 style=\"text-align: center;\"><span data-text-color=\"alert\"><strong>TOUJOURS<\/strong> \u00e0 l&rsquo;heure<\/span><\/h4>\n<p style=\"text-align: center;\">Un syst\u00e8me de rappel <br \/>et de notification efficace<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-373294167\" class=\"col medium-4 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/7.png\" class=\"attachment-medium size-medium\" alt=\"picto 100% accessible - contact EHPC Conseils pascale combabessou\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/7.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/7-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h4 style=\"text-align: center;\"><span data-text-color=\"alert\"><strong>TOUJOURS<\/strong> accessible<\/span><\/h4>\n<p style=\"text-align: center;\">Acc\u00e9dez aux outils dont<br \/>vous avez besoin 24\/7<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-844642827\" class=\"col medium-4 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-securite.png\" class=\"attachment-medium size-medium\" alt=\"picto s\u00e9curit\u00e9 assur\u00e9e - contact EHPC Conseils pascale combabessou\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-securite.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-securite-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h4 style=\"text-align: center;\"><span data-text-color=\"alert\"><strong>TOUJOURS<\/strong> prot\u00e9g\u00e9<\/span><\/h4>\n<p style=\"text-align: center;\">Acc\u00e8s priv\u00e9 et s\u00e9curis\u00e9,<br \/>conforme au RGPD<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1166123729\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1166123729 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row row-large align-center\"  id=\"row-594619223\">\n\n\n\t<div id=\"col-627445593\" class=\"col medium-4 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-modernit\u00e9.png\" class=\"attachment-medium size-medium\" alt=\"picto symbolisant la modernit\u00e9 du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 pascale combabessou - nouvelle technologie digital\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-modernit\u00e9.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-modernit\u00e9-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h4 style=\"text-align: center;\"><span data-text-color=\"alert\"><strong>TOUJOURS<\/strong> \u00e0 la pointe<\/span><\/h4>\n<p style=\"text-align: center;\">Gr\u00e2ce \u00e0 la d\u00e9mat\u00e9rialisation<br \/>des documents<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1204191856\" class=\"col medium-4 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-simplicite.png\" class=\"attachment-medium size-medium\" alt=\"picto simple d&#039;utilisation - contact EHPC Conseils pascale combabessou\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-simplicite.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-simplicite-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h4 style=\"text-align: center;\"><span data-text-color=\"alert\"><strong>TOUJOURS<\/strong> au cont\u00f4le<\/span><\/h4>\n<p style=\"text-align: center;\">La gestion de votre<br \/>entreprise est facilit\u00e9e<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1553575898\" class=\"col medium-4 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-conseils.png\" class=\"attachment-medium size-medium\" alt=\"picto symbolisant les conseils et la qualit\u00e9 du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 pascale combabessou\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-conseils.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-conseils-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h4 style=\"text-align: center;\"><span data-text-color=\"alert\"><strong>TOUJOURS<\/strong> au courant<\/span><\/h4>\n<p style=\"text-align: center;\">Recevez l&rsquo;actualit\u00e9 qui<br \/>vous int\u00e9resse<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1707289662\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1707289662 {\n  padding-top: 31px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1893534360 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(255, 255, 255);\n}\n#section_1893534360 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1893534360 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1831042309\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-875677865\">\n\n\n\t<div id=\"col-703131803\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h1 class=\"uppercase\" style=\"text-align: center;\">NOS prestations<\/h1>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:120px;\"><\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-637298572\">\n\n\n\t<div id=\"col-1085646997\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\" style=\"background-color:rgb(180, 215, 188);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1920913755\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1920913755 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center is-small\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-creation-blanc.png\" class=\"attachment-medium size-medium\" alt=\"picto symbolisant les clients (cr\u00e9ateurs d&#039;entreprise) du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 pascale combabessou mission comptable li\u00e9e \u00e0 la cr\u00e9ation d&#039;une entreprise\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-creation-blanc.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-creation-blanc-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3 style=\"color: #ffffff;\"><span data-text-color=\"alert\">Cr\u00e9ation d&rsquo;entreprise<\/span><\/h3>\n\t<div id=\"gap-1745385639\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1745385639 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a rel=\"noopener noreferrer\" href=\"https:\/\/www.ehpc-conseils.com\/index.php\/nos-prestations\/#creation\" target=\"_blank\" class=\"button white is-large\"  style=\"border-radius:99px;\">\n    <span>Voir plus<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-2045408737\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2045408737 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-612254474\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\" style=\"background-color:#b4d7bc;\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1446165847\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1446165847 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center is-small\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-suivi-comptable-blanc.png\" class=\"attachment-medium size-medium\" alt=\"picto symbolisant les missions de suivi comptable et de gestion du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 pascale combabessou picto vert et blanc\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-suivi-comptable-blanc.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-suivi-comptable-blanc-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3 style=\"color: #ffffff;\"><span data-text-color=\"alert\">Suivi comptable &amp; gestion<\/span><\/h3>\n\t<div id=\"gap-1644364536\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1644364536 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a rel=\"noopener noreferrer\" href=\"https:\/\/www.ehpc-conseils.com\/index.php\/nos-prestations\/#Suivi\" target=\"_blank\" class=\"button white is-large\"  style=\"border-radius:99px;\">\n    <span>Voir plus<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-588300737\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-588300737 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2103958206\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\" style=\"background-color:rgb(180, 215, 188);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-377090636\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-377090636 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center is-small\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-juridique-blanc.png\" class=\"attachment-medium size-medium\" alt=\"picto symbolisant les missions juridique du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 pascale combabessou picto vert et blanc\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-juridique-blanc.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-juridique-blanc-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3 style=\"color: #ffffff;\"><span data-text-color=\"alert\">Missions juridiques<\/span><\/h3>\n\t<div id=\"gap-1274109022\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1274109022 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a rel=\"noopener noreferrer\" href=\"https:\/\/www.ehpc-conseils.com\/index.php\/nos-prestations\/#missions-juridique\" target=\"_blank\" class=\"button white is-large\"  style=\"border-radius:99px;\">\n    <span>Voir plus<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-839897641\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-839897641 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-1287667728\">\n\n\n\t<div id=\"col-189422998\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\" style=\"background-color:rgb(180, 215, 188);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-274134156\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-274134156 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center is-small\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-social-blanc.png\" class=\"attachment-medium size-medium\" alt=\"picto symbolisant les missions sociales du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 pascale combabessou picto vert et blanc\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-social-blanc.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-social-blanc-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3 style=\"color: #000000;\">Missions sociales<\/h3>\n\t<div id=\"gap-560525356\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-560525356 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a rel=\"noopener noreferrer\" href=\"https:\/\/www.ehpc-conseils.com\/index.php\/nos-prestations\/#missions-sociales\" target=\"_blank\" class=\"button white is-large\"  style=\"border-radius:99px;\">\n    <span>Voir plus<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-175002190\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-175002190 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-77399130\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\" style=\"background-color:#b4d7bc;\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1270405138\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1270405138 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center is-small\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 46px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"294\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-missions-specifiques-blanc.png\" class=\"attachment-medium size-medium\" alt=\"picto symbolisant les missions sp\u00e9cifiques du cabinet d&#039;expertise comptable EHPC Conseils appartenant \u00e0 pascale combabessou picto vert et blanc\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-missions-specifiques-blanc.png 294w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/picto-missions-specifiques-blanc-150x150.png 150w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3 style=\"color: #000000;\">Missions sp\u00e9cifiques<\/h3>\n\t<div id=\"gap-547896472\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-547896472 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a rel=\"noopener noreferrer\" href=\"https:\/\/www.ehpc-conseils.com\/index.php\/nos-prestations\/#missions-spe\" target=\"_blank\" class=\"button white is-large\"  style=\"border-radius:99px;\">\n    <span>Voir plus<\/span>\n  <\/a>\n\n\n\t<div id=\"gap-1688927184\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1688927184 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1831042309 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(193, 193, 193);\n}\n#section_1831042309 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n#section_1831042309 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1831042309 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1871650539\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1871650539 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section\" id=\"section_1712435050\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle\"  id=\"row-17114529\">\n\n\n\t<div id=\"col-1016247713\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h1 class=\"uppercase\" style=\"text-align: left;\">Prendre un RDV<\/h1>\n<div class=\"is-divider divider clearfix\" style=\"max-width:120px;\"><\/div>\n\n<p style=\"text-align: left;\">Un projet ? Rencontrons-nous pour en parler de vive voix et que nous puissions vous conseiller au mieux !<\/p>\n<a href=\"https:\/\/www.ehpc-conseils.com\/index.php\/contact\/\" target=\"_self\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>Contactez-nous<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1131977255\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1716002040\">\n\t\t\t\t\t\t<div data-animate=\"fadeInDown\">\t\t<div class=\"img-inner box-shadow-2 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/rdv-ehpc-conseils.jpg\" class=\"attachment-original size-original\" alt=\"prendre RDV avec ehpc conseils\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/rdv-ehpc-conseils.jpg 900w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/rdv-ehpc-conseils-300x200.jpg 300w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/rdv-ehpc-conseils-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_1716002040 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1712435050 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255, 255, 255);\n}\n#section_1712435050 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n#section_1712435050 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1712435050 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_893214061\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-294398377\">\n\n\n\t<div id=\"col-585653277\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-939193672\">\n\n\n\t<div id=\"col-848366022\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1941557463\">\n\t\t\t\t\t\t<div data-animate=\"fadeInDown\">\t\t<div class=\"img-inner box-shadow-2 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/job-ehpc-conseils.jpg\" class=\"attachment-original size-original\" alt=\"photo d&#039;un ordinateur et d&#039;une professionnelle qui postule recrutement job ehpc conseils cabinet d&#039;expertise comptable\" srcset=\"https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/job-ehpc-conseils.jpg 1000w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/job-ehpc-conseils-300x200.jpg 300w, https:\/\/www.ehpc-conseils.com\/wp-content\/uploads\/2019\/12\/job-ehpc-conseils-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_1941557463 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1529938550\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h1 class=\"uppercase\" style=\"text-align: left;\">REJOIGNEZ-NOUS<\/h1>\n<div class=\"is-divider divider clearfix\" style=\"max-width:120px;\"><\/div>\n\n<p style=\"text-align: left;\">Vous souhaitez rejoindre un cabinet dynamique ?<br \/>Envoyez-nous votre candidature !<\/p>\n<a href=\"https:\/\/www.ehpc-conseils.com\/index.php\/recrutement\/\" target=\"_self\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>Candidature spontan\u00e9e<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_893214061 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(193, 193, 193);\n}\n#section_893214061 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n#section_893214061 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_893214061 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/pages\/15"}],"collection":[{"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":167,"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":868,"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/pages\/15\/revisions\/868"}],"wp:attachment":[{"href":"https:\/\/www.ehpc-conseils.com\/index.php\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}